{"id":6933,"date":"2019-06-12T10:00:48","date_gmt":"2019-06-12T07:00:48","guid":{"rendered":"http:\/\/ajan.africa\/?p=6933"},"modified":"2019-06-12T10:00:48","modified_gmt":"2019-06-12T07:00:48","slug":"inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles","status":"publish","type":"post","link":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/","title":{"rendered":"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles"},"content":{"rendered":"<p>Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12 au 16 ao\u00fbt 2019.<br \/>\n80 \u00e9l\u00e8ves ont particip\u00e9, tous parrain\u00e9s par les S\u0153urs de la Mis\u00e9ricorde dans leurs \u00e9tudes secondaires ou dans leurs derni\u00e8res ann\u00e9es d&#8217;\u00e9cole primaire. Comme pour le programme AHAPPY, les jeunes \u00e9taient \u00e2g\u00e9s de 13 \u00e0 21 ans, et certains d&#8217;entre eux \u00e9taient activement en r\u00e9adaptation apr\u00e8s une d\u00e9pendance \u00e0 la drogue ou un crime. Cette formation a \u00e9t\u00e9 demand\u00e9e par les S\u0153urs de la Mis\u00e9ricorde dans le cadre des activit\u00e9s de mentorat qu&#8217;elles planifient normalement pour les jeunes pendant les vacances scolaires.<br \/>\nLes S\u0153urs de la Mis\u00e9ricorde dirigent des programmes \u00e9ducatifs pour les enfants vivant dans les bidonvilles de Mukuru, dans le sud du pays, dans la banlieue de Nairobi. Ils ont cr\u00e9\u00e9 des \u00e9coles pour r\u00e9pondre aux besoins \u00e9ducatifs des enfants de ces bidonvilles. Afin de maintenir leur concentration, le bureau \u00e9ducatif des S\u0153urs de la Mis\u00e9ricorde planifie des activit\u00e9s de mentorat pour tous les enfants sous leur parrainage scolaire en fonction de leur \u00e2ge et de leur niveau d&#8217;\u00e9ducation.<br \/>\nPendant les vacances d&#8217;ao\u00fbt, le bureau de l&#8217;\u00e9ducation a pr\u00e9vu un atelier d&#8217;une semaine pour les b\u00e9n\u00e9ficiaires de 13 \u00e0 21 ans, tous \u00e0 diff\u00e9rents niveaux de l&#8217;enseignement, ceux qui sont encore dans la rue, en vue de leur r\u00e9insertion scolaire, secondaire, sup\u00e9rieure et universitaire.<br \/>\nLe programme de cinq jours comprenait le visionnement et la discussion de courtes vid\u00e9os, des spectacles tels que &#8220;spoken word&#8221;, du th\u00e9\u00e2tre, des pr\u00e9sentations d&#8217;exp\u00e9riences de vie, des po\u00e8mes, des discussions de groupe et de l&#8217;art. Ces activit\u00e9s leur ont permis d&#8217;exprimer leurs points de vue et leurs talents avec \u00e9clat.<br \/>\nUn groupe invit\u00e9 appel\u00e9 Angaza Mashinani, qui est en fait un groupe d&#8217;anciennes \u00e9l\u00e8ves b\u00e9n\u00e9ficiaires du programme S\u0153urs de la Mis\u00e9ricorde, a diverti les \u00e9l\u00e8ves \u00e0 travers un dram qui a mis en lumi\u00e8re les dangers de la violence sexuelle dans la soci\u00e9t\u00e9 des bidonvilles. Francis, le fondateur du groupe, a racont\u00e9 sa vie de toxicomane, les luttes et a inspir\u00e9 les \u00e9l\u00e8ves en leur faisant comprendre que malgr\u00e9 le fait d&#8217;avoir grandi dans les bidonvilles, on peut mener une vie r\u00e9ussie sans drogue ni crime.<br \/>\nR\u00e9actions des participants<br \/>\nNaomi;&#8217;en tant que fille, j&#8217;ai toujours voulu \u00eatre ferme dans ce que je veux. Dire non, \u00e7a devrait \u00eatre non. A partir du mois de septembre, quand je retourne \u00e0 l&#8217;\u00e9cole, je dois me comprendre moi-m\u00eame, je ne m&#8217;engage pas dans des activit\u00e9s distrayantes, je veux rester fid\u00e8le jusqu&#8217;au mariage, je ne dois pas m&#8217;engager dans la drogue parce que cela me conduira \u00e0 des comportements sexuels pr\u00e9coces parce qu&#8217;ils me rendent vuln\u00e9rables. Les vid\u00e9os ont \u00e9t\u00e9 tr\u00e8s utiles parce qu&#8217;elles m&#8217;ont expos\u00e9 \u00e0 ce qui se passe dans la communaut\u00e9 et m&#8217;ont beaucoup aid\u00e9 \u00e0 savoir quoi faire&#8221;.<br \/>\nChristopher : J&#8217;ai appris que : une mauvaise entreprise tue les r\u00eaves, la transmission des IST est aussi li\u00e9e \u00e0 la consommation de drogues, j&#8217;appr\u00e9cie de recevoir l&#8217;espoir que j&#8217;avais perdu apr\u00e8s que la pression des pairs m&#8217;a accroch\u00e9 \u00e0 la consommation de drogues.<br \/>\nL&#8217;odeur de Boaz : &#8221; \u00c9vitez les drogues, vous suivez les mauvaises personnes, elles vous induisent en erreur. Pour nous ici, ne ruinez pas les enfants des autres, c&#8217;est leur avenir, prenez soin d&#8217;eux s&#8217;il vous pla\u00eet.<br \/>\nAustin Oyoo : &#8221; Pour ne pas consommer de drogue, je dois me livrer \u00e0 des activit\u00e9s utiles.<br \/>\nWarren ouma-&#8216;J&#8217;avais peur de venir \u00e0 l&#8217;atelier. J&#8217;ai appris beaucoup de choses sur AJAN, le VIH, la drogue, l&#8217;activit\u00e9 sexuelle, le sexe avant le mariage, je vous demande \u00e0 tous ici, partagez avec notre ami dans la rue, merci.<br \/>\nDavid Okumu-&#8216;J&#8217;avais peur de parler, maintenant je suis confiant. J&#8217;\u00e9tais un drogu\u00e9, je prenais du bang, du changaa, et surtout j&#8217;\u00e9tais un voleur. J&#8217;ai appris que je dois chercher de bons mod\u00e8les. Il est difficile de trouver une m\u00e8re et un p\u00e8re qui vous poussent \u00e0 travailler dur, il est facile de trouver une momie et un p\u00e8re en sucre.<br \/>\nZephani odumbe-&#8216;L&#8217;atelier HAPPY a \u00e9t\u00e9 un programme totalement b\u00e9n\u00e9fique non seulement pour moi mais pour tous. Je tiens \u00e0 vous exhorter ici \u00e0 faire passer le message \u00e0 la maison, \u00e0 l&#8217;\u00e9cole et \u00e0 d&#8217;autres. Il faut prendre la d\u00e9cision de changer individuellement<br \/>\nS\u0153ur Rosemary Macharia, responsable des projets des S\u0153urs de la Mis\u00e9ricorde, a rappel\u00e9 aux jeunes que la vie est un graphique qui pr\u00e9sente des p\u00e9riodes productives et improductives d&#8217;une vie qui n&#8217;est pas permanente mais qui se termine pour chaque \u00eatre humain. Dans ce cas, elle les a suppli\u00e9s de veiller \u00e0 ce qu&#8217;ils vivent prudemment et de se concentrer pour tirer le meilleur parti de leur jeunesse. Elle les a encourag\u00e9s \u00e0 \u00e9viter la drogue.<br \/>\nLes formateurs de l&#8217;\u00e9poque, Pascalia Sergon, John Fisher et Steve Arodi, se sont tous dits impressionn\u00e9s par la volont\u00e9 d&#8217;apprendre des \u00e9l\u00e8ves et leur enthousiasme pour leur avenir.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-6749\" src=\"http:\/\/ajan.africa\/wp-content\/uploads\/2019\/09\/DSC02686.jpg\" alt=\"\" width=\"5472\" height=\"3648\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-6748\" src=\"http:\/\/ajan.africa\/wp-content\/uploads\/2019\/09\/DSC02679.jpg\" alt=\"\" width=\"5472\" height=\"3080\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-6747\" src=\"http:\/\/ajan.africa\/wp-content\/uploads\/2019\/09\/DSC02656.jpg\" alt=\"\" width=\"5472\" height=\"3080\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants<\/p>\n<p><a class=\"sd-more sd-all-trans\" href=\"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#more-6933\">Lire la suite<\/a><\/p>","protected":false},"author":155,"featured_media":6754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[81],"tags":[],"class_list":["post-6933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ajanews-articles-french"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dennis Owuoche\"\/>\n\t<meta name=\"google-site-verification\" content=\"Say4FGG4m7gArN7L5w7ct7RLjBmt0legSAQYrjNSIGQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AJAN - Welcome to African Jesuits AIDS Network\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Inculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN\" \/>\n\t\t<meta property=\"og:description\" content=\"Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-06-12T07:00:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-06-12T07:00:48+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricanJesuitAIDSNetwork\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AJANCenter\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Inculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AJANCenter\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#blogposting\",\"name\":\"Inculquer la confiance, l\\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN\",\"headline\":\"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles\",\"author\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/author\\\/communications\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ajan.africa\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/graphics-last-scaled.jpg\",\"width\":1920,\"height\":1081},\"datePublished\":\"2019-06-12T10:00:48+00:00\",\"dateModified\":\"2019-06-12T10:00:48+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#webpage\"},\"articleSection\":\"AJAN News Articles - French\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ajan.africa\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/category\\\/ajanews-articles-french\\\/#listItem\",\"name\":\"AJAN News Articles - French\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/category\\\/ajanews-articles-french\\\/#listItem\",\"position\":2,\"name\":\"AJAN News Articles - French\",\"item\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/category\\\/ajanews-articles-french\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#listItem\",\"name\":\"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#listItem\",\"position\":3,\"name\":\"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/category\\\/ajanews-articles-french\\\/#listItem\",\"name\":\"AJAN News Articles - French\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/#organization\",\"name\":\"African Jesuit AIDS Network (AJAN)\",\"description\":\"Welcome to African Jesuits AIDS Network\",\"url\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/\",\"telephone\":\"+254728961072\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ajan.africa\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Untitled-design-2.png\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#organizationLogo\",\"width\":112,\"height\":112},\"image\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AfricanJesuitAIDSNetwork\",\"https:\\\/\\\/twitter.com\\\/AJANCenter\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGsKQvzhzDlgOgetzDEZuTg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/author\\\/communications\\\/#author\",\"url\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/author\\\/communications\\\/\",\"name\":\"Dennis Owuoche\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b164d92bf93529dfd678de833d8dc1b1697edaa1399781f53537fb977c7585e6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dennis Owuoche\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#webpage\",\"url\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/\",\"name\":\"Inculquer la confiance, l\\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN\",\"description\":\"Les S\\u0153urs de la Mis\\u00e9ricorde ont de brillants projets \\u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\\u00e9e par AJAN du 12\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/author\\\/communications\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/author\\\/communications\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ajan.africa\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/graphics-last-scaled.jpg\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#mainImage\",\"width\":1920,\"height\":1081},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\\\/#mainImage\"},\"datePublished\":\"2019-06-12T10:00:48+00:00\",\"dateModified\":\"2019-06-12T10:00:48+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/\",\"name\":\"AJAN\",\"description\":\"Welcome to African Jesuits AIDS Network\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Inculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN","description":"Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12","canonical_url":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"Say4FGG4m7gArN7L5w7ct7RLjBmt0legSAQYrjNSIGQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#blogposting","name":"Inculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN","headline":"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles","author":{"@id":"https:\/\/ajan.africa\/fr\/author\/communications\/#author"},"publisher":{"@id":"https:\/\/ajan.africa\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg","width":1920,"height":1081},"datePublished":"2019-06-12T10:00:48+00:00","dateModified":"2019-06-12T10:00:48+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#webpage"},"isPartOf":{"@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#webpage"},"articleSection":"AJAN News Articles - French"},{"@type":"BreadcrumbList","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ajan.africa\/fr#listItem","position":1,"name":"Home","item":"https:\/\/ajan.africa\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/fr\/category\/ajanews-articles-french\/#listItem","name":"AJAN News Articles - French"}},{"@type":"ListItem","@id":"https:\/\/ajan.africa\/fr\/category\/ajanews-articles-french\/#listItem","position":2,"name":"AJAN News Articles - French","item":"https:\/\/ajan.africa\/fr\/category\/ajanews-articles-french\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#listItem","name":"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#listItem","position":3,"name":"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles","previousItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/fr\/category\/ajanews-articles-french\/#listItem","name":"AJAN News Articles - French"}}]},{"@type":"Organization","@id":"https:\/\/ajan.africa\/fr\/#organization","name":"African Jesuit AIDS Network (AJAN)","description":"Welcome to African Jesuits AIDS Network","url":"https:\/\/ajan.africa\/fr\/","telephone":"+254728961072","logo":{"@type":"ImageObject","url":"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#organizationLogo","width":112,"height":112},"image":{"@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/AfricanJesuitAIDSNetwork","https:\/\/twitter.com\/AJANCenter","https:\/\/www.youtube.com\/channel\/UCGsKQvzhzDlgOgetzDEZuTg"]},{"@type":"Person","@id":"https:\/\/ajan.africa\/fr\/author\/communications\/#author","url":"https:\/\/ajan.africa\/fr\/author\/communications\/","name":"Dennis Owuoche","image":{"@type":"ImageObject","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b164d92bf93529dfd678de833d8dc1b1697edaa1399781f53537fb977c7585e6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dennis Owuoche"}},{"@type":"WebPage","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#webpage","url":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/","name":"Inculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN","description":"Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/ajan.africa\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#breadcrumblist"},"author":{"@id":"https:\/\/ajan.africa\/fr\/author\/communications\/#author"},"creator":{"@id":"https:\/\/ajan.africa\/fr\/author\/communications\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg","@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#mainImage","width":1920,"height":1081},"primaryImageOfPage":{"@id":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/#mainImage"},"datePublished":"2019-06-12T10:00:48+00:00","dateModified":"2019-06-12T10:00:48+00:00"},{"@type":"WebSite","@id":"https:\/\/ajan.africa\/fr\/#website","url":"https:\/\/ajan.africa\/fr\/","name":"AJAN","description":"Welcome to African Jesuits AIDS Network","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/ajan.africa\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"AJAN - Welcome to African Jesuits AIDS Network","og:type":"article","og:title":"Inculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN","og:description":"Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12","og:url":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/","og:image":"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg","og:image:secure_url":"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg","og:image:width":1920,"og:image:height":1081,"article:published_time":"2019-06-12T07:00:48+00:00","article:modified_time":"2019-06-12T07:00:48+00:00","article:publisher":"https:\/\/www.facebook.com\/AfricanJesuitAIDSNetwork","twitter:card":"summary_large_image","twitter:site":"@AJANCenter","twitter:title":"Inculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles - AJAN","twitter:description":"Les S\u0153urs de la Mis\u00e9ricorde ont de brillants projets \u00e9ducatifs en faveur des enfants des bidonvilles de Nairobi. Le projet prend en compte les institutions comme l\u2019Ecole Primaire St. Catherine et le Secondaire St. Michaels dans la zone Sud B de Nairobi. Le premier a accueilli une formation des apprenants organis\u00e9e par AJAN du 12","twitter:creator":"@AJANCenter","twitter:image":"https:\/\/ajan.africa\/wp-content\/uploads\/2019\/08\/graphics-last-scaled.jpg"},"aioseo_meta_data":{"post_id":"6933","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-09 14:12:52","updated":"2025-06-06 17:35:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ajan.africa\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ajan.africa\/fr\/category\/ajanews-articles-french\/\" title=\"AJAN News Articles - French\">AJAN News Articles - French<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tInculquer la confiance, l\u2019autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ajan.africa\/fr"},{"label":"AJAN News Articles - French","link":"https:\/\/ajan.africa\/fr\/category\/ajanews-articles-french\/"},{"label":"Inculquer la confiance, l&#8217;autodiscipline afin de lutter contre le VIH SIDA dans les bidonvilles","link":"https:\/\/ajan.africa\/fr\/inculquer-la-confiance-lautodiscipline-afin-de-lutter-contre-le-vih-sida-dans-les-bidonvilles\/"}],"_links":{"self":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/posts\/6933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/users\/155"}],"replies":[{"embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/comments?post=6933"}],"version-history":[{"count":0,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/posts\/6933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/media\/6754"}],"wp:attachment":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/media?parent=6933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/categories?post=6933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/tags?post=6933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}