{"id":7822,"date":"2021-03-20T12:58:15","date_gmt":"2021-03-20T09:58:15","guid":{"rendered":"http:\/\/ajan.africa\/?p=7822"},"modified":"2021-10-26T07:47:00","modified_gmt":"2021-10-26T07:47:00","slug":"nous-sommes-appeles-a-vivre-pour-les-autres","status":"publish","type":"post","link":"https:\/\/ajan.africa\/fr\/nous-sommes-appeles-a-vivre-pour-les-autres\/","title":{"rendered":"Nous sommes appel\u00e9s \u00e0 vivre pour les autres"},"content":{"rendered":"<h6><em><strong>P\u00e8re V\u00e9daste NKESHIMANA, SJ.<\/strong><\/em><\/h6>\n<p>Face \u00e0 la souffrance, il est normal que l&#8217;on se sente effray\u00e9 et agisse pour am\u00e9liorer la situation. Et toute personne de bonne volont\u00e9 agirait pour aider ceux qui ne peuvent pas sortir de leur d\u00e9tresse. C\u2019est pourquoi il est difficile de comprendre la souffrance de J\u00e9sus. \u00c9tait-il impuissant? Si celui qui doit nous sauver est celui qui souffre, y a-t-il une autre issue pour les afflig\u00e9s? Les lectures de ce 5e dimanche de Car\u00eame nous aident \u00e0 voir que c&#8217;est par sa souffrance que J\u00e9sus est glorifi\u00e9. Ce qui est pour le monde la d\u00e9faite et la honte est pour lui la victoire et la gloire. En effet, J\u00e9sus souffre pour que l\u2019amour soit victorieux parmi les \u00eatres humains et que chaque \u00eatre humain puisse vivre diff\u00e9remment, en suivant le chemin de J\u00e9sus.<\/p>\n<p>J\u00e9sus nous enseigne comment vivre non pas pour soi&nbsp;mais plut\u00f4t vivre les uns pour les autres. En d\u2019autres termes, J\u00e9sus souffre pour partager la vie de Dieu avec chaque \u00eatre humain qui n\u2019est rien d\u2019autre que l\u2019amour de Dieu. Il est donc important de conna\u00eetre la puissance de l\u2019amour qui sous-tend l\u2019action courageuse de J\u00e9sus vers la souffrance pour le salut du monde. Cet amour inconditionnel et sans fin a toujours \u00e9t\u00e9 caract\u00e9ristique des actes de Dieu. Lorsque J\u00e9r\u00e9mie parle d&#8217;une nouvelle alliance, ce n&#8217;est pas parce que les Juifs ont chang\u00e9. C&#8217;est Dieu qui leur a donn\u00e9 une nouvelle chance de r\u00e9cup\u00e9rer ce qu&#8217;ils ont perdu \u00e0 cause de leur infid\u00e9lit\u00e9: \u00abJe mettrai ma loi en eux, et je l&#8217;\u00e9crirai dans leur c\u0153ur; et je serai leur Dieu, et ils seront mon peuple \u00bb (J\u00e9r. 31&nbsp;: 33). Ainsi, la nouvelle alliance vise \u00e0 faire comprendre aux Juifs qui est leur Dieu et c&#8217;est une initiative libre de Dieu. J\u00e9sus ob\u00e9issant \u00e0 cet amour accomplit la proph\u00e9tie de J\u00e9r\u00e9mie en touchant chaque c\u0153ur humain avec son amour de l\u2019humain jusqu\u2019\u00e0 la fin.<\/p>\n<p>La pand\u00e9mie de COVID-19 nous a fait r\u00e9aliser \u00e0 quel point nous d\u00e9pendons les uns des autres. \u00c0 mon avis, si toutes les Nations s&#8217;\u00e9taient mobilis\u00e9es comme un seul homme contre le COVID-19, cela n&#8217;aurait peut-\u00eatre pas fait autant de victimes. On pourrait en dire autant pour d&#8217;autres maladies comme le VIH\/SIDA, la tuberculose, etc. Tant que les gens n\u2019ont pas de compassion les uns pour les autres, tant que les Nations sont dirig\u00e9es par l\u2019\u00e9go\u00efsme ou le tribalisme, l\u2019amour inconditionnel et excessif de Dieu est toujours n\u00e9cessaire.<\/p>\n<p>Le d\u00e9fi est de diff\u00e9rencier nos victoires apparentes de la victoire de J\u00e9sus qui a vaincu la mort. Si J\u00e9sus s&#8217;\u00e9tait battu de la mani\u00e8re habituelle, il aurait vaincu tous ses ennemis. Mais ce triomphe aurait \u00e9t\u00e9 fortuit. Pour voir le succ\u00e8s \u00e0 la mani\u00e8re de J\u00e9sus, il faut voir le monde diff\u00e9remment, voir au-del\u00e0 des faits, ce qui, dans ce cas, est avoir des yeux de foi. \u00ab\u00c0 moins qu&#8217;un grain de bl\u00e9 ne tombe en terre et ne meure, il reste seul; mais s&#8217;il meurt, il porte beaucoup de fruit \u00bb pr\u00e9cise l\u2019&nbsp;\u00e9vang\u00e9liste Jean (Jn. 12&nbsp;:24). Suivre J\u00e9sus, c&#8217;est se concentrer sur les fruits qui r\u00e9sultent des actes d&#8217;amour et de ne pas s&#8217;inqui\u00e9ter de la douleur qui peut \u00eatre subie dans le processus. J\u00e9sus est le grain de bl\u00e9 qui est mort pour laisser place \u00e0 un \u00e9pi dont tous les \u00eatres humains jouissent. Il aurait pu aimer \u00eatre le Fils de Dieu, mais il a laiss\u00e9 tous ses privil\u00e8ges afin d&#8217;\u00e9lever les \u00eatres humains \u00e0 sa nature divine. Dans le monde, on parle des droits de l&#8217;homme. Mais pour le chr\u00e9tien, celui qui suit J\u00e9sus renonce ce \u00e0 quoi il\/elle a droit pour am\u00e9liorer la vie des plus n\u00e9cessiteux.<\/p>\n<p>Certes, on pourrait penser que l&#8217;amour est dangereux s&#8217;il conduit \u00e0 des souffrances telles que celles que J\u00e9sus a endur\u00e9es. Cependant, nous pouvons voir une grandeur qui est transparente dans un tel amour et devrait inspirer tous les disciples de J\u00e9sus. Ce n&#8217;est pas facile pour J\u00e9sus comme il dit: \u00abP\u00e8re, si tu le veux, \u00e9loigne de moi cette coupe; cependant, non pas ma volont\u00e9, mais que la tienne soit faite\u00bb (Lc 22&nbsp;:42). Mais ob\u00e9issant \u00e0 la volont\u00e9 de Dieu, Il a vaincu la peur. On nous rappelle que suivre J\u00e9sus n\u2019est pas seulement pour des bons moments que les humains ont tendance \u00e0 appr\u00e9cier, mais pour accepter que la volont\u00e9 de Dieu pr\u00e9vaut sur nos peurs et nos tendances. Nous devons recevoir la chose la plus importante que J\u00e9sus nous a donn\u00e9e: sa vie. Et cela ne peut pas \u00eatre sa vie si elle n&#8217;est pas donn\u00e9e comme il s&#8217;est donn\u00e9 \u00e0 nous. Son Amour transcende tout.<\/p>\n<p>Le car\u00eame est un moment privil\u00e9gi\u00e9 de conversion, de je\u00fbne et de partage. Que ce dimanche nous aide \u00e0 faire un pas de plus en cultivant parmi nous des actes d&#8217;amour et de pardon, en nous donnant mutuellement un nouveau d\u00e9part.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>P\u00e8re V\u00e9daste NKESHIMANA, SJ. Face \u00e0 la souffrance, il est normal que l&#8217;on se sente effray\u00e9 et agisse pour am\u00e9liorer la situation. Et toute personne de bonne volont\u00e9 agirait pour aider ceux qui ne peuvent pas sortir de leur d\u00e9tresse. C\u2019est pourquoi il est difficile de comprendre la souffrance de<\/p>\n<p><a class=\"sd-more sd-all-trans\" href=\"https:\/\/ajan.africa\/fr\/nous-sommes-appeles-a-vivre-pour-les-autres\/#more-7822\">Lire la suite<\/a><\/p>","protected":false},"author":155,"featured_media":7818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[98],"tags":[],"class_list":["post-7822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ajan-news-articles"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/posts\/7822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/users\/155"}],"replies":[{"embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/comments?post=7822"}],"version-history":[{"count":0,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/posts\/7822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/media\/7818"}],"wp:attachment":[{"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/media?parent=7822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/categories?post=7822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajan.africa\/fr\/wp-json\/wp\/v2\/tags?post=7822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}