{"id":7199,"date":"2020-02-05T07:21:52","date_gmt":"2020-02-05T04:21:52","guid":{"rendered":"http:\/\/ajan.africa\/?p=7199"},"modified":"2020-02-05T07:21:52","modified_gmt":"2020-02-05T04:21:52","slug":"le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee","status":"publish","type":"post","link":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/","title":{"rendered":"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\u00e9e"},"content":{"rendered":"<p><strong>Por Caleb Mwamisi<\/strong><\/p>\n<p>L&#8217;Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu&#8217;elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n&#8217;ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres menaces \u00e0 la s\u00e9curit\u00e9 des adolescents sont la violence et le suicide.<\/p>\n<p>Ceci est un grand rappel de la menace que le VIH et le sida continuent de faire peser sur l&#8217;avenir de l&#8217;humanit\u00e9 malgr\u00e9 les progr\u00e8s r\u00e9alis\u00e9s pour r\u00e9duire son impact d\u00e9vastateur dans le monde, o\u00f9 l&#8217;Afrique porte le plus lourd fardeau de la maladie. Elle menace sans aucun doute la prochaine g\u00e9n\u00e9ration.<\/p>\n<p>L&#8217;OMS recommande de fournir les outils n\u00e9cessaires pour \u00e9duquer les adolescents sur la sexualit\u00e9, la toxicomanie et la sant\u00e9 mentale, une action qui, selon elle, peut r\u00e9duire consid\u00e9rablement le nombre de d\u00e9c\u00e8s.<\/p>\n<p>Outre la promotion de la s\u00e9curit\u00e9 des adolescents, les autres questions urgentes que l&#8217;organisation identifie sont les suivantes : se concentrer sur la sant\u00e9 tout en discutant du changement climatique, fournir des soins de sant\u00e9 aux nations en crise, rendre les soins de sant\u00e9 accessibles \u00e0 tous, \u00e9largir l&#8217;acc\u00e8s aux vaccins et aux m\u00e9dicaments, lutter contre les maladies transmissibles, se pr\u00e9parer aux \u00e9pid\u00e9mies, rendre les aliments sains plus accessibles, investir dans les travailleurs de la sant\u00e9, renforcer la confiance entre les syst\u00e8mes de soins de sant\u00e9 et le public, utiliser les technologies modernes et les innovations, pr\u00e9venir la r\u00e9sistance aux antibiotiques et veiller \u00e0 ce que les \u00e9tablissements de soins de sant\u00e9 soient propres et st\u00e9riles.<\/p>\n<p>Ceci est un nouvel \u00e9veil de conscience \u00e0 l\u2019\u00e9gard de l&#8217;Afrique, qui est la plus touch\u00e9e par le VIH et le sida, puisque les derniers chiffres de l&#8217;ONUSIDA montrent que plus de 69 % des PVVIH se trouvent en Afrique subsaharienne.<\/p>\n<p>La liste de l&#8217;OMS a \u00e9t\u00e9 publi\u00e9e par le Dr Tedros Adhanom Ghebreyesus, Directeur G\u00e9n\u00e9ral de l&#8217;agence.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Par Caleb Mwamisi L&#8217;Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu&#8217;elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n&#8217;ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la<\/p>\n<p><a class=\"sd-more sd-all-trans\" href=\"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#more-7199\">consulte Mais informa\u00e7\u00e3o<\/a><\/p>","protected":false},"author":155,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[81],"tags":[],"class_list":["post-7199","post","type-post","status-publish","format-standard","hentry","category-ajanews-articles-french"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Par Caleb Mwamisi L&#039;Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu&#039;elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n&#039;ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dennis Owuoche\"\/>\n\t<meta name=\"google-site-verification\" content=\"Say4FGG4m7gArN7L5w7ct7RLjBmt0legSAQYrjNSIGQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AJAN - Welcome to African Jesuits AIDS Network\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Le VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e - AJAN\" \/>\n\t\t<meta property=\"og:description\" content=\"Par Caleb Mwamisi L&#039;Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu&#039;elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n&#039;ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"112\" \/>\n\t\t<meta property=\"og:image:height\" content=\"112\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-05T04:21:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-05T04:21:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AfricanJesuitAIDSNetwork\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AJANCenter\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Le VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e - AJAN\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Par Caleb Mwamisi L&#039;Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu&#039;elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n&#039;ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AJANCenter\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#blogposting\",\"name\":\"Le VIH et le sida parmi les tueurs de plus d\\u2019un million d\\u2019adolescents dans le monde chaque ann\\u00e9e - AJAN\",\"headline\":\"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\\u00e9e\",\"author\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/author\\\/communications\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ajan.africa\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Untitled-design-2.png\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/#articleImage\",\"width\":112,\"height\":112},\"datePublished\":\"2020-02-05T07:21:52+00:00\",\"dateModified\":\"2020-02-05T07:21:52+00:00\",\"inLanguage\":\"pt-PT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#webpage\"},\"articleSection\":\"AJAN News Articles - French\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ajan.africa\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/category\\\/ajanews-articles-french\\\/#listItem\",\"name\":\"AJAN News Articles - French\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/category\\\/ajanews-articles-french\\\/#listItem\",\"position\":2,\"name\":\"AJAN News Articles - French\",\"item\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/category\\\/ajanews-articles-french\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#listItem\",\"name\":\"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\\u00e9e\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#listItem\",\"position\":3,\"name\":\"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\\u00e9e\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/category\\\/ajanews-articles-french\\\/#listItem\",\"name\":\"AJAN News Articles - French\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/#organization\",\"name\":\"African Jesuit AIDS Network (AJAN)\",\"description\":\"Welcome to African Jesuits AIDS Network\",\"url\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/\",\"telephone\":\"+254728961072\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ajan.africa\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Untitled-design-2.png\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#organizationLogo\",\"width\":112,\"height\":112},\"image\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AfricanJesuitAIDSNetwork\",\"https:\\\/\\\/twitter.com\\\/AJANCenter\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGsKQvzhzDlgOgetzDEZuTg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/author\\\/communications\\\/#author\",\"url\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/author\\\/communications\\\/\",\"name\":\"Dennis Owuoche\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b164d92bf93529dfd678de833d8dc1b1697edaa1399781f53537fb977c7585e6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dennis Owuoche\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#webpage\",\"url\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/\",\"name\":\"Le VIH et le sida parmi les tueurs de plus d\\u2019un million d\\u2019adolescents dans le monde chaque ann\\u00e9e - AJAN\",\"description\":\"Par Caleb Mwamisi L'Organisation mondiale de la sant\\u00e9 a r\\u00e9cemment publi\\u00e9 une liste de 13 probl\\u00e8mes de sant\\u00e9 urgents qu'elle a identifi\\u00e9s et qui devront \\u00eatre trait\\u00e9s au cours de la prochaine d\\u00e9cennie. Le VIH et le sida n'ont pas \\u00e9t\\u00e9 oubli\\u00e9s parmi les questions \\u00e0 traiter pour promouvoir la s\\u00e9curit\\u00e9 des adolescents. Les autres\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/author\\\/communications\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/author\\\/communications\\\/#author\"},\"datePublished\":\"2020-02-05T07:21:52+00:00\",\"dateModified\":\"2020-02-05T07:21:52+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/\",\"name\":\"AJAN\",\"description\":\"Welcome to African Jesuits AIDS Network\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/ajan.africa\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Le VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e - AJAN","description":"Par Caleb Mwamisi L'Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu'elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n'ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres","canonical_url":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"Say4FGG4m7gArN7L5w7ct7RLjBmt0legSAQYrjNSIGQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#blogposting","name":"Le VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e - AJAN","headline":"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\u00e9e","author":{"@id":"https:\/\/ajan.africa\/pt\/author\/communications\/#author"},"publisher":{"@id":"https:\/\/ajan.africa\/pt\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png","@id":"https:\/\/ajan.africa\/pt\/#articleImage","width":112,"height":112},"datePublished":"2020-02-05T07:21:52+00:00","dateModified":"2020-02-05T07:21:52+00:00","inLanguage":"pt-PT","mainEntityOfPage":{"@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#webpage"},"isPartOf":{"@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#webpage"},"articleSection":"AJAN News Articles - French"},{"@type":"BreadcrumbList","@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ajan.africa\/pt#listItem","position":1,"name":"Home","item":"https:\/\/ajan.africa\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/pt\/category\/ajanews-articles-french\/#listItem","name":"AJAN News Articles - French"}},{"@type":"ListItem","@id":"https:\/\/ajan.africa\/pt\/category\/ajanews-articles-french\/#listItem","position":2,"name":"AJAN News Articles - French","item":"https:\/\/ajan.africa\/pt\/category\/ajanews-articles-french\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#listItem","name":"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\u00e9e"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/pt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#listItem","position":3,"name":"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\u00e9e","previousItem":{"@type":"ListItem","@id":"https:\/\/ajan.africa\/pt\/category\/ajanews-articles-french\/#listItem","name":"AJAN News Articles - French"}}]},{"@type":"Organization","@id":"https:\/\/ajan.africa\/pt\/#organization","name":"African Jesuit AIDS Network (AJAN)","description":"Welcome to African Jesuits AIDS Network","url":"https:\/\/ajan.africa\/pt\/","telephone":"+254728961072","logo":{"@type":"ImageObject","url":"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png","@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#organizationLogo","width":112,"height":112},"image":{"@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/AfricanJesuitAIDSNetwork","https:\/\/twitter.com\/AJANCenter","https:\/\/www.youtube.com\/channel\/UCGsKQvzhzDlgOgetzDEZuTg"]},{"@type":"Person","@id":"https:\/\/ajan.africa\/pt\/author\/communications\/#author","url":"https:\/\/ajan.africa\/pt\/author\/communications\/","name":"Dennis Owuoche","image":{"@type":"ImageObject","@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b164d92bf93529dfd678de833d8dc1b1697edaa1399781f53537fb977c7585e6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dennis Owuoche"}},{"@type":"WebPage","@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#webpage","url":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/","name":"Le VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e - AJAN","description":"Par Caleb Mwamisi L'Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu'elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n'ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/ajan.africa\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/#breadcrumblist"},"author":{"@id":"https:\/\/ajan.africa\/pt\/author\/communications\/#author"},"creator":{"@id":"https:\/\/ajan.africa\/pt\/author\/communications\/#author"},"datePublished":"2020-02-05T07:21:52+00:00","dateModified":"2020-02-05T07:21:52+00:00"},{"@type":"WebSite","@id":"https:\/\/ajan.africa\/pt\/#website","url":"https:\/\/ajan.africa\/pt\/","name":"AJAN","description":"Welcome to African Jesuits AIDS Network","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/ajan.africa\/pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"AJAN - Welcome to African Jesuits AIDS Network","og:type":"article","og:title":"Le VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e - AJAN","og:description":"Par Caleb Mwamisi L'Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu'elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n'ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres","og:url":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/","og:image":"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png","og:image:secure_url":"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png","og:image:width":112,"og:image:height":112,"article:published_time":"2020-02-05T04:21:52+00:00","article:modified_time":"2020-02-05T04:21:52+00:00","article:publisher":"https:\/\/www.facebook.com\/AfricanJesuitAIDSNetwork","twitter:card":"summary_large_image","twitter:site":"@AJANCenter","twitter:title":"Le VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e - AJAN","twitter:description":"Par Caleb Mwamisi L'Organisation mondiale de la sant\u00e9 a r\u00e9cemment publi\u00e9 une liste de 13 probl\u00e8mes de sant\u00e9 urgents qu'elle a identifi\u00e9s et qui devront \u00eatre trait\u00e9s au cours de la prochaine d\u00e9cennie. Le VIH et le sida n'ont pas \u00e9t\u00e9 oubli\u00e9s parmi les questions \u00e0 traiter pour promouvoir la s\u00e9curit\u00e9 des adolescents. Les autres","twitter:creator":"@AJANCenter","twitter:image":"https:\/\/ajan.africa\/wp-content\/uploads\/2023\/05\/Untitled-design-2.png"},"aioseo_meta_data":{"post_id":"7199","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-09 14:21:03","updated":"2025-06-06 17:40:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ajan.africa\/pt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ajan.africa\/pt\/category\/ajanews-articles-french\/\" title=\"AJAN News Articles - French\">AJAN News Articles - French<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLe VIH et le sida parmi les tueurs de plus d\u2019un million d\u2019adolescents dans le monde chaque ann\u00e9e\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ajan.africa\/pt"},{"label":"AJAN News Articles - French","link":"https:\/\/ajan.africa\/pt\/category\/ajanews-articles-french\/"},{"label":"Le VIH et le sida parmi les tueurs de plus d&#8217;un million d&#8217;adolescents dans le monde chaque ann\u00e9e","link":"https:\/\/ajan.africa\/pt\/le-vih-et-le-sida-parmi-les-tueurs-de-plus-dun-million-dadolescents-dans-le-monde-chaque-annee\/"}],"_links":{"self":[{"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/posts\/7199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/users\/155"}],"replies":[{"embeddable":true,"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/comments?post=7199"}],"version-history":[{"count":0,"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/posts\/7199\/revisions"}],"wp:attachment":[{"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/media?parent=7199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/categories?post=7199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajan.africa\/pt\/wp-json\/wp\/v2\/tags?post=7199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}